{"id":245,"count":3,"description":"","link":"https:\/\/www.portugalresidencyadvisors.com\/es\/categorias\/residencia\/ciudadanos-de-la-ue\/","name":"Ciudadanos de la UE","slug":"ciudadanos-de-la-ue","taxonomy":"category","parent":84,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ciudadanos de la UE Listings 1 | Portugal Residency Advisors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.portugalresidencyadvisors.com\/es\/categorias\/residencia\/ciudadanos-de-la-ue\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ciudadanos de la UE Listings 1 | Portugal Residency Advisors\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.portugalresidencyadvisors.com\/es\/categorias\/residencia\/ciudadanos-de-la-ue\/\" \/>\n<meta property=\"og:site_name\" content=\"Portugal Residency Advisors\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.portugalresidencyadvisors.com\/wp-content\/uploads\/2023\/04\/cover-nhr-tax-regime-portugal-residency-advisors.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ptadvresidency\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/categorias\\\/residencia\\\/ciudadanos-de-la-ue\\\/\",\"url\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/categorias\\\/residencia\\\/ciudadanos-de-la-ue\\\/\",\"name\":\"Ciudadanos de la UE Listings 1 | Portugal Residency Advisors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/categorias\\\/residencia\\\/ciudadanos-de-la-ue\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/categorias\\\/residencia\\\/ciudadanos-de-la-ue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visados\",\"item\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/categorias\\\/residencia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ciudadanos de la UE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/\",\"name\":\"Portugal Residency Advisors\",\"description\":\"We help individuals wishing to work, study, retire, invest or moving to Portugal\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/#organization\"},\"alternateName\":\"Portugal Residency Made Easy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/#organization\",\"name\":\"Asesores de residencia en Portugal\",\"alternateName\":\"PTADV - Portugal Residency Advisors Unipessoal, Lda\",\"url\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Logotipo-Versao-Principal-01.png\",\"contentUrl\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Logotipo-Versao-Principal-01.png\",\"width\":1772,\"height\":1182,\"caption\":\"Asesores de residencia en Portugal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portugalresidencyadvisors.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portugalresidencyadvisors\",\"https:\\\/\\\/x.com\\\/ptadvresidency\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/portugal-residency-advisors\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ciudadanos de la UE Listings 1 | Portugal Residency Advisors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.portugalresidencyadvisors.com\/es\/categorias\/residencia\/ciudadanos-de-la-ue\/","og_locale":"es_ES","og_type":"article","og_title":"Ciudadanos de la UE Listings 1 | Portugal Residency Advisors","og_url":"https:\/\/www.portugalresidencyadvisors.com\/es\/categorias\/residencia\/ciudadanos-de-la-ue\/","og_site_name":"Portugal Residency Advisors","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.portugalresidencyadvisors.com\/wp-content\/uploads\/2023\/04\/cover-nhr-tax-regime-portugal-residency-advisors.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ptadvresidency","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.portugalresidencyadvisors.com\/es\/categorias\/residencia\/ciudadanos-de-la-ue\/","url":"https:\/\/www.portugalresidencyadvisors.com\/es\/categorias\/residencia\/ciudadanos-de-la-ue\/","name":"Ciudadanos de la UE Listings 1 | Portugal Residency Advisors","isPartOf":{"@id":"https:\/\/www.portugalresidencyadvisors.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.portugalresidencyadvisors.com\/es\/categorias\/residencia\/ciudadanos-de-la-ue\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.portugalresidencyadvisors.com\/es\/categorias\/residencia\/ciudadanos-de-la-ue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.portugalresidencyadvisors.com\/es\/"},{"@type":"ListItem","position":2,"name":"Visados","item":"https:\/\/www.portugalresidencyadvisors.com\/es\/categorias\/residencia\/"},{"@type":"ListItem","position":3,"name":"Ciudadanos de la UE"}]},{"@type":"WebSite","@id":"https:\/\/www.portugalresidencyadvisors.com\/es\/#website","url":"https:\/\/www.portugalresidencyadvisors.com\/es\/","name":"Portugal Residency Advisors","description":"We help individuals wishing to work, study, retire, invest or moving to Portugal","publisher":{"@id":"https:\/\/www.portugalresidencyadvisors.com\/es\/#organization"},"alternateName":"Portugal Residency Made Easy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.portugalresidencyadvisors.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.portugalresidencyadvisors.com\/es\/#organization","name":"Asesores de residencia en Portugal","alternateName":"PTADV - Portugal Residency Advisors Unipessoal, Lda","url":"https:\/\/www.portugalresidencyadvisors.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.portugalresidencyadvisors.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.portugalresidencyadvisors.com\/wp-content\/uploads\/2023\/03\/Logotipo-Versao-Principal-01.png","contentUrl":"https:\/\/www.portugalresidencyadvisors.com\/wp-content\/uploads\/2023\/03\/Logotipo-Versao-Principal-01.png","width":1772,"height":1182,"caption":"Asesores de residencia en Portugal"},"image":{"@id":"https:\/\/www.portugalresidencyadvisors.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portugalresidencyadvisors","https:\/\/x.com\/ptadvresidency","https:\/\/www.linkedin.com\/company\/portugal-residency-advisors\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.portugalresidencyadvisors.com\/es\/wp-json\/wp\/v2\/categories\/245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portugalresidencyadvisors.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.portugalresidencyadvisors.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.portugalresidencyadvisors.com\/es\/wp-json\/wp\/v2\/categories\/84"}],"wp:post_type":[{"href":"https:\/\/www.portugalresidencyadvisors.com\/es\/wp-json\/wp\/v2\/posts?categories=245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}